{"id":9952,"date":"2025-07-30T12:02:18","date_gmt":"2025-07-30T10:02:18","guid":{"rendered":"https:\/\/www.companyiahomenots.com\/inicio\/"},"modified":"2025-10-29T11:01:19","modified_gmt":"2025-10-29T10:01:19","slug":"inicio","status":"publish","type":"page","link":"https:\/\/www.companyiahomenots.com\/es\/","title":{"rendered":"Inicio"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_image=\u00bbhttps:\/\/www.companyiahomenots.com\/wp-content\/uploads\/companyia-homenots-home-slider.webp\u00bb positioning=\u00bbnone\u00bb custom_padding=\u00bb12em||1em||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb custom_padding=\u00bb||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bb|700|||||||\u00bb header_text_color=\u00bb#FFFFFF\u00bb header_font_size=\u00bb40px\u00bb header_line_height=\u00bb1.2em\u00bb max_width=\u00bb550px\u00bb header_font_size_tablet=\u00bb35px\u00bb header_font_size_phone=\u00bb30px\u00bb header_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1>La m\u00e1xima aspiraci\u00f3n de cualquier persona es ser feliz, \u00bfa qu\u00e9 venimos a este mundo si no?<\/h1>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#FFFFFF\u00bb max_width=\u00bb550px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Todos y todas tenemos <strong>una idea de felicidad<\/strong>; la nuestra es <strong>ver las sonrisa<\/strong>s de los ni\u00f1os y las ni\u00f1as y de sus familias pasando juntos un buen rato.<\/p>\n<p><\/p>\n<p>En un mundo que nos empuja a la individualidad y a las prisas, nosotros os proponemos parar, mirarnos a los ojos y, con la ayuda de la m\u00fasica, construir un espacio com\u00fan donde divertirnos y recordar c\u00f3mo puede ser de diferente el mundo visto con los ojos de un ni\u00f1o.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_css_main_element=\u00bbdisplay: flex;||flex-flow: wrap;\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_button button_url=\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjkyNjQifX0=@\u00bb button_text=\u00bbLa compa\u00f1\u00eda\u00bb module_class=\u00bbboton\u00bb _builder_version=\u00bb4.27.4&#8243; _dynamic_attributes=\u00bbbutton_url\u00bb _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_text_color=\u00bb#FFFFFF\u00bb button_bg_color=\u00bb#9f691d\u00bb button_border_width=\u00bb1px\u00bb button_border_color=\u00bb#9f691d\u00bb button_border_radius=\u00bb30px\u00bb button_font=\u00bb|700|||||||\u00bb button_use_icon=\u00bboff\u00bb custom_margin=\u00bb|1em|||false|false\u00bb custom_padding=\u00bb0.5em|1.5em|0.5em|1.5em|true|true\u00bb custom_css_main_element=\u00bbwidth:fit-content !important;||min-width:fit-content !important;||max-width:fit-content !important;||display:block !important;\u00bb custom_css_free_form=\u00bbselector{||  width:fit-content !important;||  min-width:fit-content !important;||  max-width:fit-content !important;||  display:block !important;||}\u00bb global_colors_info=\u00bb{}\u00bb button_bg_color__hover_enabled=\u00bbon|hover\u00bb button_bg_color__hover=\u00bbRGBA(255,255,255,0)\u00bb button_bg_enable_color__hover=\u00bbon\u00bb][\/et_pb_button][et_pb_button button_url=\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjgyNjEifX0=@\u00bb button_text=\u00bb\u00a1Contacta ahora!\u00bb module_class=\u00bbboton\u00bb _builder_version=\u00bb4.27.4&#8243; _dynamic_attributes=\u00bbbutton_url\u00bb _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_text_color=\u00bb#FFFFFF\u00bb button_bg_color=\u00bbRGBA(255,255,255,0)\u00bb button_border_width=\u00bb1px\u00bb button_border_color=\u00bb#9f691d\u00bb button_border_radius=\u00bb30px\u00bb button_font=\u00bb|700|||||||\u00bb button_use_icon=\u00bboff\u00bb custom_padding=\u00bb0.5em|1.5em|0.5em|1.5em|true|true\u00bb custom_css_main_element=\u00bbwidth:fit-content !important;||min-width:fit-content !important;||max-width:fit-content !important;||display:block !important;\u00bb custom_css_free_form=\u00bbselector{||  width:fit-content !important;||  min-width:fit-content !important;||  max-width:fit-content !important;||  display:block !important;||}\u00bb global_colors_info=\u00bb{}\u00bb button_bg_color__hover_enabled=\u00bbon|hover\u00bb button_bg_color__hover=\u00bb#9f691d\u00bb button_bg_enable_color__hover=\u00bbon\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0px||0px||true|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb2em||2em||true|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_2_font=\u00bb|700|||||||\u00bb header_2_text_align=\u00bbcenter\u00bb header_2_font_size=\u00bb30px\u00bb custom_margin=\u00bb||1em||false|false\u00bb custom_padding=\u00bb||0em||false|false\u00bb header_2_font_size_tablet=\u00bb30px\u00bb header_2_font_size_phone=\u00bb25px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb custom_css_free_form=\u00bbselector h2{||  padding-bottom:0px !important;||}\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Espect\u00e1culos<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_orientation=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Aqu\u00ed podr\u00e1s encontrar <strong>informaci\u00f3n sobre los espect\u00e1culos<\/strong> de la compa\u00f1\u00eda<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb||1em||false|false\u00bb custom_padding=\u00bb1em||1em||true|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/www.companyiahomenots.com\/wp-content\/uploads\/companyia-homenots-espectacles-bum-tresor-pirata.webp\u00bb title_text=\u00bbcompanyia-homenots-espectacles-bum-tresor-pirata\u00bb show_bottom_space=\u00bboff\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb max_width=\u00bb450px\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb||2em||false|false\u00bb border_radii=\u00bbon|20px|20px|20px|20px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_3_font=\u00bb|700|||||||\u00bb header_3_text_align=\u00bbcenter\u00bb custom_margin=\u00bb||1em||false|false\u00bb header_3_font_size_tablet=\u00bb\u00bb header_3_font_size_phone=\u00bb20px\u00bb header_3_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>Bum y el tesoro del pirata<\/h3>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjgyODMifX0=@\u00bb button_text=\u00bbSaber m\u00e1s\u00bb button_alignment=\u00bbcenter\u00bb module_class=\u00bbboton\u00bb _builder_version=\u00bb4.27.4&#8243; _dynamic_attributes=\u00bbbutton_url\u00bb _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_text_color=\u00bb#FFFFFF\u00bb button_bg_color=\u00bb#9f691d\u00bb button_border_width=\u00bb1px\u00bb button_border_color=\u00bb#9f691d\u00bb button_border_radius=\u00bb30px\u00bb button_font=\u00bb|700|||||||\u00bb button_use_icon=\u00bboff\u00bb custom_margin=\u00bb||||false|false\u00bb custom_padding=\u00bb0.5em|1.5em|0.5em|1.5em|true|true\u00bb global_colors_info=\u00bb{}\u00bb button_bg_color__hover_enabled=\u00bbon|hover\u00bb button_bg_color__hover=\u00bbRGBA(255,255,255,0)\u00bb button_bg_enable_color__hover=\u00bbon\u00bb button_text_color__hover_enabled=\u00bbon|hover\u00bb button_text_color__hover=\u00bb#000000&#8243;][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/www.companyiahomenots.com\/wp-content\/uploads\/companyia-homenots-espectacles-bum-llibre-magic.webp\u00bb title_text=\u00bbcompanyia-homenots-espectacles-bum-llibre-magic\u00bb show_bottom_space=\u00bboff\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb max_width=\u00bb450px\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb||2em||false|false\u00bb border_radii=\u00bbon|20px|20px|20px|20px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_3_font=\u00bb|700|||||||\u00bb header_3_text_align=\u00bbcenter\u00bb custom_margin=\u00bb||1em||false|false\u00bb header_3_font_size_tablet=\u00bb\u00bb header_3_font_size_phone=\u00bb20px\u00bb header_3_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>Bum y el libro m\u00e1gico de las hadas<\/h3>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjgyODUifX0=@\u00bb button_text=\u00bbSaber m\u00e1s\u00bb button_alignment=\u00bbcenter\u00bb module_class=\u00bbboton\u00bb _builder_version=\u00bb4.27.4&#8243; _dynamic_attributes=\u00bbbutton_url\u00bb _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_text_color=\u00bb#FFFFFF\u00bb button_bg_color=\u00bb#9f691d\u00bb button_border_width=\u00bb1px\u00bb button_border_color=\u00bb#9f691d\u00bb button_border_radius=\u00bb30px\u00bb button_font=\u00bb|700|||||||\u00bb button_use_icon=\u00bboff\u00bb custom_margin=\u00bb||||false|false\u00bb custom_padding=\u00bb0.5em|1.5em|0.5em|1.5em|true|true\u00bb global_colors_info=\u00bb{}\u00bb button_bg_color__hover_enabled=\u00bbon|hover\u00bb button_bg_color__hover=\u00bbRGBA(255,255,255,0)\u00bb button_bg_enable_color__hover=\u00bbon\u00bb button_text_color__hover=\u00bb#000000&#8243; button_text_color__hover_enabled=\u00bbon|hover\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb||2em||false|false\u00bb custom_padding=\u00bb1em||1em||true|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/www.companyiahomenots.com\/wp-content\/uploads\/companyia-homenots-espectacles-bum-estel-desitjos.webp\u00bb title_text=\u00bbcompanyia-homenots-espectacles-bum-estel-desitjos\u00bb show_bottom_space=\u00bboff\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb max_width=\u00bb450px\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb||2em||false|false\u00bb border_radii=\u00bbon|20px|20px|20px|20px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_3_font=\u00bb|700|||||||\u00bb header_3_text_align=\u00bbcenter\u00bb custom_margin=\u00bb||1em||false|false\u00bb header_3_font_size_tablet=\u00bb\u00bb header_3_font_size_phone=\u00bb20px\u00bb header_3_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>Bum y la estrella de los deseos<\/h3>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjgyODcifX0=@\u00bb button_text=\u00bbSaber m\u00e1s\u00bb button_alignment=\u00bbcenter\u00bb module_class=\u00bbboton\u00bb _builder_version=\u00bb4.27.4&#8243; _dynamic_attributes=\u00bbbutton_url\u00bb _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_text_color=\u00bb#FFFFFF\u00bb button_bg_color=\u00bb#9f691d\u00bb button_border_width=\u00bb1px\u00bb button_border_color=\u00bb#9f691d\u00bb button_border_radius=\u00bb30px\u00bb button_font=\u00bb|700|||||||\u00bb button_use_icon=\u00bboff\u00bb custom_margin=\u00bb||||false|false\u00bb custom_padding=\u00bb0.5em|1.5em|0.5em|1.5em|true|true\u00bb global_colors_info=\u00bb{}\u00bb button_bg_color__hover_enabled=\u00bbon|hover\u00bb button_bg_color__hover=\u00bbRGBA(255,255,255,0)\u00bb button_bg_enable_color__hover=\u00bbon\u00bb button_text_color__hover=\u00bb#000000&#8243; button_text_color__hover_enabled=\u00bbon|hover\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/www.companyiahomenots.com\/wp-content\/uploads\/companyia-homenots-espectacles-bum-secret-amistat.webp\u00bb title_text=\u00bbcompanyia-homenots-espectacles-bum-secret-amistat\u00bb show_bottom_space=\u00bboff\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb max_width=\u00bb450px\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb||2em||false|false\u00bb border_radii=\u00bbon|20px|20px|20px|20px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_3_font=\u00bb|700|||||||\u00bb header_3_text_align=\u00bbcenter\u00bb custom_margin=\u00bb||1em||false|false\u00bb header_3_font_size_tablet=\u00bb\u00bb header_3_font_size_phone=\u00bb20px\u00bb header_3_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>Bum y el secreto de la amistad<\/h3>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjgyODkifX0=@\u00bb button_text=\u00bbSaber m\u00e1s\u00bb button_alignment=\u00bbcenter\u00bb module_class=\u00bbboton\u00bb _builder_version=\u00bb4.27.4&#8243; _dynamic_attributes=\u00bbbutton_url\u00bb _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_text_color=\u00bb#FFFFFF\u00bb button_bg_color=\u00bb#9f691d\u00bb button_border_width=\u00bb1px\u00bb button_border_color=\u00bb#9f691d\u00bb button_border_radius=\u00bb30px\u00bb button_font=\u00bb|700|||||||\u00bb button_use_icon=\u00bboff\u00bb custom_margin=\u00bb||||false|false\u00bb custom_padding=\u00bb0.5em|1.5em|0.5em|1.5em|true|true\u00bb global_colors_info=\u00bb{}\u00bb button_bg_color__hover_enabled=\u00bbon|hover\u00bb button_bg_color__hover=\u00bbRGBA(255,255,255,0)\u00bb button_bg_enable_color__hover=\u00bbon\u00bb button_text_color__hover=\u00bb#000000&#8243; button_text_color__hover_enabled=\u00bbon|hover\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#f8f7ff\u00bb custom_padding=\u00bb0px||0px||true|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb3em||3em||true|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_2_font=\u00bb|700|||||||\u00bb header_2_text_align=\u00bbcenter\u00bb header_2_font_size=\u00bb30px\u00bb custom_margin=\u00bb||1em||false|false\u00bb custom_padding=\u00bb||0em||false|false\u00bb header_2_font_size_tablet=\u00bb30px\u00bb header_2_font_size_phone=\u00bb25px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb custom_css_free_form=\u00bbselector h2{||  padding-bottom:0px !important;||}\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Agenda<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_orientation=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>A continuaci\u00f3n pod\u00e9is encontrar el detalle de todas las actuaciones de la compa\u00f1\u00eda para los pr\u00f3ximos meses.<\/p>\n<p>[\/et_pb_text][et_pb_code _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb max_width=\u00bb550px\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb||0px||false|false\u00bb custom_padding=\u00bb||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<div class=\"simcal-calendar simcal-default-calendar simcal-default-calendar-list simcal-default-calendar-light\" data-calendar-id=\"9313\" data-timezone=\"Europe\/Madrid\" data-offset=\"7200\" data-week-start=\"1\" data-calendar-start=\"1778623200\" data-calendar-end=\"1779121800\" data-events-first=\"1778860800\" data-events-last=\"1779121800\"><div class=\"simcal-calendar-list \"><dl class=\"simcal-events-list-container\" data-prev=\"1747087200\" data-next=\"1810159200\" data-heading-small=\"May 2026\" data-heading-large=\"mayo 2026\">\t<dt class=\"simcal-day-label\" style=\"border-bottom: 1px solid #000000;\" ><span style=\"background-color: #000000; color: #ffffff;\"><span class=\"simcal-date-format\" data-date-format=\"d F Y\">15 mayo 2026<\/span> <\/span><\/dt>\n<dd class=\"simcal-weekday-5 simcal-past simcal-day simcal-day-has-events simcal-day-has-1-events simcal-events-calendar-9313\" data-events-count=\"1\">\n\t<ul class=\"simcal-events\">\n\t<li class=\"simcal-event simcal-event-has-location simcal-events-calendar-9313\" style=\"\" itemscope itemtype=\"http:\/\/schema.org\/Event\" data-start=\"1778860800\">\n\t\t<div class=\"simcal-event-details\"><p><strong><span class=\"simcal-event-title\" itemprop=\"name\">En BUM i el tresor del pirata<\/span><\/strong><\/p>\n<p><span class=\"simcal-event-start simcal-event-start-date\" data-event-start=\"1778860800\" data-event-format=\"d F Y\" itemprop=\"startDate\" content=\"2026-05-15T18:00:00+02:00\">15 mayo 2026<\/span>&nbsp;@&nbsp;<span class=\"simcal-event-start simcal-event-start-time\" data-event-start=\"1778860800\" data-event-format=\"g:i a\" itemprop=\"startDate\" content=\"2026-05-15T18:00:00+02:00\">6:00 pm<\/span> - <span class=\"simcal-event-end simcal-event-end-time\" data-event-end=\"1778864400\" data-event-format=\"g:i a\" itemprop=\"endDate\" content=\"2026-05-15T19:00:00+02:00\">7:00 pm<\/span><br \/>\n <span class=\"simcal-event-address simcal-event-start-location\" itemprop=\"location\" itemscope itemtype=\"http:\/\/schema.org\/Place\"><meta itemprop=\"name\" content=\"Biblioteca de Campdev\u00e0nol, Pla\u00e7a d&#039;Anselm Clav\u00e9, s\/n, 17530 Campdev\u00e0nol, Girona, Espanya\" \/><meta itemprop=\"address\" content=\"Biblioteca de Campdev\u00e0nol, Pla\u00e7a d&#039;Anselm Clav\u00e9, s\/n, 17530 Campdev\u00e0nol, Girona, Espanya\" \/>Biblioteca de Campdev\u00e0nol, Pla\u00e7a d&#039;Anselm Clav\u00e9, s\/n, 17530 Campdev\u00e0nol, Girona, Espanya<\/span><\/p>\n<div><\/div><\/div>\n\t<\/li>\n<\/ul>\n\n<\/dd>\n\t<dt class=\"simcal-day-label\" style=\"border-bottom: 1px solid #000000;\" ><span style=\"background-color: #000000; color: #ffffff;\"><span class=\"simcal-date-format\" data-date-format=\"d F Y\">16 mayo 2026<\/span> <\/span><\/dt>\n<dd class=\"simcal-weekday-6 simcal-past simcal-day simcal-day-has-events simcal-day-has-1-events simcal-events-calendar-9313\" data-events-count=\"1\">\n\t<ul class=\"simcal-events\">\n\t<li class=\"simcal-event simcal-event-has-location simcal-events-calendar-9313\" style=\"\" itemscope itemtype=\"http:\/\/schema.org\/Event\" data-start=\"1778920200\">\n\t\t<div class=\"simcal-event-details\"><p><strong><span class=\"simcal-event-title\" itemprop=\"name\">En BUM i el tresor del pirata<\/span><\/strong><\/p>\n<p><span class=\"simcal-event-start simcal-event-start-date\" data-event-start=\"1778920200\" data-event-format=\"d F Y\" itemprop=\"startDate\" content=\"2026-05-16T10:30:00+02:00\">16 mayo 2026<\/span>&nbsp;@&nbsp;<span class=\"simcal-event-start simcal-event-start-time\" data-event-start=\"1778920200\" data-event-format=\"g:i a\" itemprop=\"startDate\" content=\"2026-05-16T10:30:00+02:00\">10:30 am<\/span> - <span class=\"simcal-event-end simcal-event-end-time\" data-event-end=\"1778923800\" data-event-format=\"g:i a\" itemprop=\"endDate\" content=\"2026-05-16T11:30:00+02:00\">11:30 am<\/span><br \/>\n <span class=\"simcal-event-address simcal-event-start-location\" itemprop=\"location\" itemscope itemtype=\"http:\/\/schema.org\/Place\"><meta itemprop=\"name\" content=\"Biblioteca P\u00fablica del Govern d&#039;Andorra, AD500 Andorra la Vella, Andorra\" \/><meta itemprop=\"address\" content=\"Biblioteca P\u00fablica del Govern d&#039;Andorra, AD500 Andorra la Vella, Andorra\" \/>Biblioteca P\u00fablica del Govern d&#039;Andorra, AD500 Andorra la Vella, Andorra<\/span><\/p>\n<div><\/div><\/div>\n\t<\/li>\n<\/ul>\n\n<\/dd>\n\t<dt class=\"simcal-day-label\" style=\"border-bottom: 1px solid #000000;\" ><span style=\"background-color: #000000; color: #ffffff;\"><span class=\"simcal-date-format\" data-date-format=\"d F Y\">18 mayo 2026<\/span> <\/span><\/dt>\n<dd class=\"simcal-weekday-1 simcal-past simcal-day simcal-day-has-events simcal-day-has-1-events simcal-events-calendar-9313\" data-events-count=\"1\">\n\t<ul class=\"simcal-events\">\n\t<li class=\"simcal-event simcal-event-has-location simcal-events-calendar-9313\" style=\"\" itemscope itemtype=\"http:\/\/schema.org\/Event\" data-start=\"1779118200\">\n\t\t<div class=\"simcal-event-details\"><p><strong><span class=\"simcal-event-title\" itemprop=\"name\">En BUM i l&#039;estel dels desitjos<\/span><\/strong><\/p>\n<p><span class=\"simcal-event-start simcal-event-start-date\" data-event-start=\"1779118200\" data-event-format=\"d F Y\" itemprop=\"startDate\" content=\"2026-05-18T17:30:00+02:00\">18 mayo 2026<\/span>&nbsp;@&nbsp;<span class=\"simcal-event-start simcal-event-start-time\" data-event-start=\"1779118200\" data-event-format=\"g:i a\" itemprop=\"startDate\" content=\"2026-05-18T17:30:00+02:00\">5:30 pm<\/span> - <span class=\"simcal-event-end simcal-event-end-time\" data-event-end=\"1779121800\" data-event-format=\"g:i a\" itemprop=\"endDate\" content=\"2026-05-18T18:30:00+02:00\">6:30 pm<\/span><br \/>\n <span class=\"simcal-event-address simcal-event-start-location\" itemprop=\"location\" itemscope itemtype=\"http:\/\/schema.org\/Place\"><meta itemprop=\"name\" content=\"Biblioteca de Montgat\u2014Tirant lo Blanc, Ronda dels Pa\u00efsos Catalans, 08390 Montgat, Barcelona, Espanya\" \/><meta itemprop=\"address\" content=\"Biblioteca de Montgat\u2014Tirant lo Blanc, Ronda dels Pa\u00efsos Catalans, 08390 Montgat, Barcelona, Espanya\" \/>Biblioteca de Montgat\u2014Tirant lo Blanc, Ronda dels Pa\u00efsos Catalans, 08390 Montgat, Barcelona, Espanya<\/span><\/p>\n<div><\/div><\/div>\n\t<\/li>\n<\/ul>\n\n<\/dd>\n<\/dl><div class=\"simcal-ajax-loader simcal-spinner-top\" style=\"display: none;\"><i class=\"simcal-icon-spinner simcal-icon-spin\"><\/i><\/div><\/div><\/div>[\/et_pb_code][et_pb_button button_url=\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjgyNTgifX0=@\u00bb button_text=\u00bbVer Agenda\u00bb button_alignment=\u00bbcenter\u00bb module_class=\u00bbboton\u00bb _builder_version=\u00bb4.27.4&#8243; _dynamic_attributes=\u00bbbutton_url\u00bb _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_text_color=\u00bb#000000&#8243; button_bg_color=\u00bbRGBA(255,255,255,0)\u00bb button_border_width=\u00bb1px\u00bb button_border_color=\u00bb#9f691d\u00bb button_border_radius=\u00bb30px\u00bb button_font=\u00bb|700|||||||\u00bb button_use_icon=\u00bboff\u00bb custom_padding=\u00bb0.5em|1.5em|0.5em|1.5em|true|true\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb button_bg_color__hover_enabled=\u00bbon|hover\u00bb button_bg_color__hover=\u00bb#9f691d\u00bb button_bg_enable_color__hover=\u00bbon\u00bb button_text_color__hover_enabled=\u00bbon|hover\u00bb button_text_color__hover=\u00bb#FFFFFF\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; module_id=\u00bbnoticias-home\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0px||0px||true|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb3em||0em||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_2_font=\u00bb|700|||||||\u00bb header_2_text_align=\u00bbcenter\u00bb header_2_font_size=\u00bb30px\u00bb custom_margin=\u00bb||1em||false|false\u00bb custom_padding=\u00bb||0em||false|false\u00bb header_2_font_size_tablet=\u00bb30px\u00bb header_2_font_size_phone=\u00bb25px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb custom_css_free_form=\u00bbselector h2{||  padding-bottom:0px !important;||}\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Noticias<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_orientation=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>En esta secci\u00f3n <strong>repasamos la actividad de la compa\u00f1\u00eda<\/strong> y te ponemos al d\u00eda de todas las novedades.<\/p>\n<p>[\/et_pb_text][et_pb_blog fullwidth=\u00bboff\u00bb posts_number=\u00bb3&#8243; include_categories=\u00bball\u00bb excerpt_length=\u00bb120&#8243; show_more=\u00bbon\u00bb show_author=\u00bboff\u00bb show_date=\u00bboff\u00bb show_categories=\u00bboff\u00bb show_pagination=\u00bboff\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bb|700|||||||\u00bb header_font_size=\u00bb22px\u00bb header_line_height=\u00bb1.2em\u00bb body_text_color=\u00bb#000000&#8243; read_more_font=\u00bb|700|||||||\u00bb read_more_text_color=\u00bb#FFFFFF\u00bb hover_enabled=\u00bb0&#8243; custom_css_free_form=\u00bbselector article{||  border:none !important;||  text-align:center;||}||selector img{||  border-radius:10px;||}\u00bb custom_css_read_more=\u00bbwidth:fit-content;||padding:0.6em 2em;||background-color:#9f691d;||display:block;||border-radius:30px;||margin:0px auto;||margin-top:1em;||border:1px solid #9f691d;\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb read_more_text_color__hover_enabled=\u00bbon|hover\u00bb read_more_text_color__hover=\u00bb#000000&#8243; custom_css_read_more__hover_enabled=\u00bbon|hover\u00bb sticky_enabled=\u00bb0&#8243; custom_css_read_more__hover=\u00bbwidth:fit-content;||padding:0.6em 2em;||background-color:transparent;||color:black;||display:block;||border-radius:30px;||margin:0px auto;||margin-top:1em;\u00bb][\/et_pb_blog][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb||2em||false|false\u00bb custom_padding=\u00bb1em||1em||true|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_button button_url=\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjEwIn19@\u00bb button_text=\u00bbM\u00e1s Noticias\u00bb button_alignment=\u00bbcenter\u00bb module_class=\u00bbboton\u00bb _builder_version=\u00bb4.27.4&#8243; _dynamic_attributes=\u00bbbutton_url\u00bb _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_text_color=\u00bb#000000&#8243; button_bg_color=\u00bbRGBA(255,255,255,0)\u00bb button_border_width=\u00bb1px\u00bb button_border_color=\u00bb#9f691d\u00bb button_border_radius=\u00bb30px\u00bb button_font=\u00bb|700|||||||\u00bb button_use_icon=\u00bboff\u00bb custom_padding=\u00bb0.5em|1.5em|0.5em|1.5em|true|true\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb button_bg_color__hover_enabled=\u00bbon|hover\u00bb button_bg_color__hover=\u00bb#9f691d\u00bb button_bg_enable_color__hover=\u00bbon\u00bb button_text_color__hover_enabled=\u00bbon|hover\u00bb button_text_color__hover=\u00bb#FFFFFF\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La m\u00e1xima aspiraci\u00f3n de cualquier persona es ser feliz, \u00bfa qu\u00e9 venimos a este mundo si no?Todos y todas tenemos una idea de felicidad; la nuestra es ver las sonrisas de los ni\u00f1os y las ni\u00f1as y de sus familias pasando juntos un buen rato.En un mundo que nos empuja a la individualidad y a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"class_list":["post-9952","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Espect\u00e1culos infantiles | Companyia Homenots<\/title>\n<meta name=\"description\" content=\"Espect\u00e1culos infantiles llenos de m\u00fasica, magia y sonrisas para disfrutar en familia con la Companyia Homenots.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.companyiahomenots.com\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Espect\u00e1culos infantiles | Companyia Homenots\" \/>\n<meta property=\"og:description\" content=\"Espect\u00e1culos infantiles llenos de m\u00fasica, magia y sonrisas para disfrutar en familia con la Companyia Homenots.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.companyiahomenots.com\/\" \/>\n<meta property=\"og:site_name\" content=\"Companyia Homenots\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-29T10:01:19+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.companyiahomenots.com\/\",\"url\":\"https:\/\/www.companyiahomenots.com\/\",\"name\":\"Espect\u00e1culos infantiles | Companyia Homenots\",\"isPartOf\":{\"@id\":\"https:\/\/www.companyiahomenots.com\/#website\"},\"datePublished\":\"2025-07-30T10:02:18+00:00\",\"dateModified\":\"2025-10-29T10:01:19+00:00\",\"description\":\"Espect\u00e1culos infantiles llenos de m\u00fasica, magia y sonrisas para disfrutar en familia con la Companyia Homenots.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.companyiahomenots.com\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.companyiahomenots.com\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.companyiahomenots.com\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.companyiahomenots.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inicio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.companyiahomenots.com\/#website\",\"url\":\"https:\/\/www.companyiahomenots.com\/\",\"name\":\"Companyia Homenots\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.companyiahomenots.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Espect\u00e1culos infantiles | Companyia Homenots","description":"Espect\u00e1culos infantiles llenos de m\u00fasica, magia y sonrisas para disfrutar en familia con la Companyia Homenots.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.companyiahomenots.com\/","og_locale":"es_ES","og_type":"article","og_title":"Espect\u00e1culos infantiles | Companyia Homenots","og_description":"Espect\u00e1culos infantiles llenos de m\u00fasica, magia y sonrisas para disfrutar en familia con la Companyia Homenots.","og_url":"https:\/\/www.companyiahomenots.com\/","og_site_name":"Companyia Homenots","article_modified_time":"2025-10-29T10:01:19+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.companyiahomenots.com\/","url":"https:\/\/www.companyiahomenots.com\/","name":"Espect\u00e1culos infantiles | Companyia Homenots","isPartOf":{"@id":"https:\/\/www.companyiahomenots.com\/#website"},"datePublished":"2025-07-30T10:02:18+00:00","dateModified":"2025-10-29T10:01:19+00:00","description":"Espect\u00e1culos infantiles llenos de m\u00fasica, magia y sonrisas para disfrutar en familia con la Companyia Homenots.","breadcrumb":{"@id":"https:\/\/www.companyiahomenots.com\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.companyiahomenots.com\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.companyiahomenots.com\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.companyiahomenots.com\/"},{"@type":"ListItem","position":2,"name":"Inicio"}]},{"@type":"WebSite","@id":"https:\/\/www.companyiahomenots.com\/#website","url":"https:\/\/www.companyiahomenots.com\/","name":"Companyia Homenots","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.companyiahomenots.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.companyiahomenots.com\/es\/wp-json\/wp\/v2\/pages\/9952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.companyiahomenots.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.companyiahomenots.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.companyiahomenots.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.companyiahomenots.com\/es\/wp-json\/wp\/v2\/comments?post=9952"}],"version-history":[{"count":13,"href":"https:\/\/www.companyiahomenots.com\/es\/wp-json\/wp\/v2\/pages\/9952\/revisions"}],"predecessor-version":[{"id":10195,"href":"https:\/\/www.companyiahomenots.com\/es\/wp-json\/wp\/v2\/pages\/9952\/revisions\/10195"}],"wp:attachment":[{"href":"https:\/\/www.companyiahomenots.com\/es\/wp-json\/wp\/v2\/media?parent=9952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}